{"id":1527,"date":"2026-05-13T11:35:25","date_gmt":"2026-05-13T02:35:25","guid":{"rendered":"https:\/\/abeshokai.jp\/blog\/remus\/?p=1527"},"modified":"2026-05-13T11:35:25","modified_gmt":"2026-05-13T02:35:25","slug":"audi-tt%e7%94%a8%e3%83%ac%e3%83%a0%e3%82%b9%e3%83%9e%e3%83%95%e3%83%a9%e3%83%bc%e8%a3%85%e7%9d%80%e7%b4%b9%e4%bb%8b","status":"publish","type":"post","link":"https:\/\/abeshokai.jp\/blog\/remus\/audi\/audi-tt%e7%94%a8%e3%83%ac%e3%83%a0%e3%82%b9%e3%83%9e%e3%83%95%e3%83%a9%e3%83%bc%e8%a3%85%e7%9d%80%e7%b4%b9%e4%bb%8b","title":{"rendered":"Audi TT\u7528\u30ec\u30e0\u30b9\u30de\u30d5\u30e9\u30fc\u88c5\u7740\u7d39\u4ecb"},"content":{"rendered":"<p>\u4eca\u65e5\u306fAudiTTS\u306e2.0\u30a8\u30f3\u30b8\u30f3\u306e\u30dd\u30c6\u30f3\u30b7\u30e3\u30eb\u3092\u5f15\u304d\u51fa\u3057\u307e\u3059\uff01<\/p>\n<p>\u30d0\u30eb\u30d6\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u7d99\u627f\/\u80cc\u5727\u4f4e\u6e1b\/\u30d0\u30f3\u30d1\u30fc\u306e\u6a2a\u30e9\u30a4\u30f3\u306b\u5408\u308f\u305b\u305f\u30bb\u30ec\u30af\u30bf\u30d6\u30eb\u306a\u30a2\u30f3\u30b0\u30eb\u578b\u30c6\u30fc\u30eb\u30a8\u30f3\u30c9<\/p>\n<p>\u4f4e\u97f3\u304c\u5f37\u8abf\u3055\u308c\u308b\u7a81\u304d\u629c\u3051\u308b\u3088\u3046\u306a\u30b9\u30dd\u30fc\u30c4\u30b5\u30a6\u30f3\u30c9\/\u30aa\u30b9\u30b9\u30e1\u30a2\u30a4\u30c6\u30e0\/\u3067\u3059\u3002<\/p>\n<p>\u4eca\u56de\u306e\u3054\u88c5\u7740\u306f\u9577\u91ce\u306e\u30e9\u30f3\u30ca\u30a6\u30a7\u30a4\u69d8\u3067\u9802\u304d\u307e\u3057\u305f\uff01\u3042\u308a\u304c\u3068\u3046\u3054\u3056\u3044\u307e\u3057\u305f\u3002<\/p>\n<p>TT\/TTS\u9069\u5408\u306f<a href=\"https:\/\/abeshokai.jp\/remus\/l_audi.html\">\u3053\u3061\u3089\u304b\u3089<\/a><\/p>\n<p><img loading=\"lazy\" class=\"alignnone  wp-image-1528\" src=\"https:\/\/abeshokai.jp\/blog\/remus\/wp-content\/uploads\/2026\/05\/TTS-8s-audi01.png\" alt=\"\" width=\"777\" height=\"574\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone  wp-image-1529\" src=\"https:\/\/abeshokai.jp\/blog\/remus\/wp-content\/uploads\/2026\/05\/tts32.png\" alt=\"\" width=\"768\" height=\"574\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone  wp-image-1530\" src=\"https:\/\/abeshokai.jp\/blog\/remus\/wp-content\/uploads\/2026\/05\/tts78.png\" alt=\"\" width=\"767\" height=\"604\" \/><\/p>\n<p><img loading=\"lazy\" class=\"alignnone  wp-image-1531\" src=\"https:\/\/abeshokai.jp\/blog\/remus\/wp-content\/uploads\/2026\/05\/tts852.png\" alt=\"\" width=\"767\" height=\"565\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4eca\u65e5\u306fAudiTTS\u306e2.0\u30a8\u30f3\u30b8\u30f3\u306e\u30dd\u30c6\u30f3\u30b7\u30e3\u30eb\u3092\u5f15\u304d\u51fa\u3057\u307e\u3059\uff01 \u30d0\u30eb\u30d6\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u7d99\u627f\/\u80cc\u5727\u4f4e\u6e1b\/\u30d0\u30f3\u30d1\u30fc\u306e\u6a2a\u30e9\u30a4\u30f3\u306b\u5408\u308f\u305b\u305f\u30bb\u30ec\u30af\u30bf\u30d6\u30eb\u306a\u30a2\u30f3\u30b0\u30eb\u578b\u30c6\u30fc\u30eb\u30a8\u30f3\u30c9 \u4f4e\u97f3\u304c\u5f37\u8abf\u3055\u308c\u308b\u7a81\u304d\u629c\u3051\u308b\u3088\u3046\u306a\u30b9\u30dd\u30fc\u30c4\u30b5\u30a6\u30f3\u30c9\/\u30aa [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/posts\/1527"}],"collection":[{"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":2,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/posts\/1527\/revisions"}],"predecessor-version":[{"id":1533,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/posts\/1527\/revisions\/1533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/media?parent=1527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/categories?post=1527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abeshokai.jp\/blog\/remus\/wp-json\/wp\/v2\/tags?post=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}